{"id":2848,"date":"2022-09-12T21:54:38","date_gmt":"2022-09-12T21:54:38","guid":{"rendered":"https:\/\/www.escuelamasterchef.com\/?post_type=videos&#038;p=2848"},"modified":"2023-04-17T18:21:52","modified_gmt":"2023-04-17T18:21:52","slug":"langostinos-al-cava-y-almendras","status":"publish","type":"videos","link":"https:\/\/www.escuelamasterchef.com\/en\/videos\/langostinos-al-cava-y-almendras\/","title":{"rendered":"Langostinos al cava y almendras"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":9,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"class_list":["post-2848","videos","type-videos","status-publish","hentry"],"acf":{"titulo":"Langostinos al cava y almendras.","url":"https:\/\/vimeo.com\/746225012","descripcion":"","preparacion":"1. Retirar el intestino del animal. Una vez realices este paso, podemos marinar nuestro marisco.\r\n2. Ponemos el cava los dientes de ajo picados, pimienta negra y perejil picado muy fino. Deja marinar durante unos 30 minutos en la nevera para que penetre este sabor en el marisco.\r\n3. Llevamos una sart\u00e9n con aceite a fuego medio.\r\n4. Agrega las almendras dejamos dorar ligeramente y a\u00f1adimos la cebolla en dados muy finos y saltea.\r\n5. A\u00f1adimos los langostinos bien escurridos de la marinada.\r\n6. Siempre debemos tener cuidado al cocinar mariscos para que no se pasen de cocci\u00f3n.\r\n7. A\u00f1ade el cava y deja que se evapore el alcohol para poder realizar la salsa, si deseas puedes bajar la intensidad del fuego.\r\n8. Una vez evaporado el alcohol del cava, puedes a\u00f1adir un poco de mantequilla para ligar la salsa.\r\n9. Lo tendremos listo para comer.","ingredientes":"500 Gramos de Langostinos\r\n1 Copa de Cava\r\n5 Gramos de Perejil\r\n1 Cebolla\r\n1 Cucharadita de Mantequilla\r\n20 Gramos de Almendras\r\nSal\r\n1 Pizca de Pimienta negra\r\n3 o 4 dientes de ajo picados.","utensilios":"-Cuchillo\r\n-Bol\r\n-Sart\u00e9n\r\n-Copa de cava\r\n-Cucharilla de caf\u00e9","nombre_del_instructor":"Carlos Maldonado","imagen_instructor":"https:\/\/static.capabiliaserver.com\/frontend\/clients\/masterchef\/wp_dev\/wp-content\/uploads\/2022\/09\/4de76580-carlos-maldonado.jpg","producto":{"ID":2229,"post_author":"3","post_date":"2022-09-13 02:59:58","post_date_gmt":"2022-09-13 02:59:58","post_content":"contenido","post_title":"COCINA EN 30 MINUTOS","post_excerpt":"Si no tienes mucho tiempo para estar en la cocina, este curso es para ti. ","post_status":"publish","comment_status":"open","ping_status":"closed","post_password":"","post_name":"cocina-en-30-minutos","to_ping":"","pinged":"","post_modified":"2022-09-16 17:42:06","post_modified_gmt":"2022-09-16 17:42:06","post_content_filtered":"","post_parent":0,"guid":"https:\/\/www.escuelamasterchef.com\/?post_type=product&#038;p=2229","menu_order":0,"post_type":"product","post_mime_type":"","comment_count":"0","filter":"raw"}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Langostinos al cava y almendras - Capabilia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Langostinos al cava y almendras - Capabilia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/\" \/>\n<meta property=\"og:site_name\" content=\"Capabilia\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-17T18:21:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/\",\"url\":\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/\",\"name\":\"Langostinos al cava y almendras - Capabilia\",\"isPartOf\":{\"@id\":\"https:\/\/www.escuelamasterchef.com\/#website\"},\"datePublished\":\"2022-09-12T21:54:38+00:00\",\"dateModified\":\"2023-04-17T18:21:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Videos\",\"item\":\"https:\/\/www.escuelamasterchef.com\/videos\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Langostinos al cava y almendras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.escuelamasterchef.com\/#website\",\"url\":\"https:\/\/www.escuelamasterchef.com\/\",\"name\":\"Capabilia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.escuelamasterchef.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Langostinos al cava y almendras - Capabilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/","og_locale":"en_US","og_type":"article","og_title":"Langostinos al cava y almendras - Capabilia","og_url":"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/","og_site_name":"Capabilia","article_modified_time":"2023-04-17T18:21:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/","url":"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/","name":"Langostinos al cava y almendras - Capabilia","isPartOf":{"@id":"https:\/\/www.escuelamasterchef.com\/#website"},"datePublished":"2022-09-12T21:54:38+00:00","dateModified":"2023-04-17T18:21:52+00:00","breadcrumb":{"@id":"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.escuelamasterchef.com\/videos\/langostinos-al-cava-y-almendras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Videos","item":"https:\/\/www.escuelamasterchef.com\/videos\/"},{"@type":"ListItem","position":2,"name":"Langostinos al cava y almendras"}]},{"@type":"WebSite","@id":"https:\/\/www.escuelamasterchef.com\/#website","url":"https:\/\/www.escuelamasterchef.com\/","name":"Capabilia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escuelamasterchef.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/videos\/2848"}],"collection":[{"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/videos"}],"about":[{"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/types\/videos"}],"author":[{"embeddable":true,"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/comments?post=2848"}],"version-history":[{"count":5,"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/videos\/2848\/revisions"}],"predecessor-version":[{"id":5025,"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/videos\/2848\/revisions\/5025"}],"wp:attachment":[{"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/media?parent=2848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escuelamasterchef.com\/en\/wp-json\/wp\/v2\/categories?post=2848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}